{"id":3019,"date":"2023-07-03T13:41:20","date_gmt":"2023-07-03T12:41:20","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?p=3019"},"modified":"2023-07-03T13:41:20","modified_gmt":"2023-07-03T12:41:20","slug":"offre-de-cdd-charge-e-denquetes-et-dedition-de-deux-livres-blancs-en-etudes-areales-h-f-gis-asie-et-gis-momm","status":"publish","type":"post","link":"http:\/\/amiens-sociologie.fr\/index.php\/2023\/07\/03\/offre-de-cdd-charge-e-denquetes-et-dedition-de-deux-livres-blancs-en-etudes-areales-h-f-gis-asie-et-gis-momm\/","title":{"rendered":"Offre de CDD : Charg\u00e9-e d&#8217;enqu\u00eates et d&#8217;\u00e9dition de deux livres blancs en \u00e9tudes ar\u00e9ales (H\/F) &#8211; GIS Asie et GIS MOMM"},"content":{"rendered":"\n<h1><\/h1>\n\n\n\n<p>Pour postuler : <\/p>\n\n\n\n<p><a href=\"https:\/\/emploi.cnrs.fr\/Offres\/CDD\/UAR2999-RICARO-002\/Default.aspx\">https:\/\/emploi.cnrs.fr\/Offres\/CDD\/UAR2999-RICARO-002\/Default.aspx<\/a><\/p>\n\n\n\n<p>Date Limite Candidature : vendredi 21 juillet 2023<\/p>\n\n\n\n<p>Assurez-vous que votre <a href=\"https:\/\/emploi.cnrs.fr\/Candidat\/Profil\/Default.aspx\">profil candidat<\/a> soit correctement renseign\u00e9 avant de postuler. Les informations de votre profil compl\u00e8tent celles associ\u00e9es \u00e0 chaque candidature. Afin d\u2019augmenter votre visibilit\u00e9 sur notre Portail Emploi et ainsi permettre aux recruteurs de consulter votre profil candidat, vous avez la possibilit\u00e9 de d\u00e9poser votre CV dans notre <a href=\"https:\/\/emploi.cnrs.fr\/Candidat\/Profil\/VisibiliteProfil.aspx\">CVTh\u00e8que<\/a> en un clic !<\/p>\n\n\n\n<h3>Informations g\u00e9n\u00e9rales<\/h3>\n\n\n\n<p><strong>Intitul\u00e9 de l&#8217;offre : Charg\u00e9 d&#8217;enqu\u00eates et d&#8217;\u00e9dition de deux livres blancs en \u00e9tudes ar\u00e9ales (H\/F) &#8211; GIS Asie et GIS MOMM<\/strong><br>R\u00e9f\u00e9rence : UAR2999-RICARO-002<br>Nombre de Postes : 1<br>Lieu de travail : AUBERVILLIERS<br>Date de publication : vendredi 30 juin 2023<br>Type de contrat : CDD Technique\/Administratif<br>Dur\u00e9e du contrat : 12 mois<br>Date d&#8217;embauche pr\u00e9vue : 1 novembre 2023<br>Quotit\u00e9 de travail : Temps complet<br>R\u00e9mun\u00e9ration : 2280 \u20ac salaire brut mensuel<br>Niveau d&#8217;\u00e9tudes souhait\u00e9 : Niveau 6 &#8211; (Bac+3 ou 4)<br>Exp\u00e9rience souhait\u00e9e : Indiff\u00e9rent<br>BAP : Culture, Communication, Production et diffusion des savoirs<br>Emploi type : Editeur-trice<br><\/p>\n\n\n\n<h3>Missions<\/h3>\n\n\n\n<p>Coordonner la mise en \u0153uvre et assister le comit\u00e9 de pilotage et\/ou la direction du GIS dans la r\u00e9alisation d&#8217;un livre blanc des \u00e9tudes sur les mondes iraniens et persans en France, et la finalisation d&#8217;un livre blanc sur les \u00e9tudes extr\u00eame-orientales.<\/p>\n\n\n\n<h3>Activit\u00e9s<\/h3>\n\n\n\n<p>L&#8217;activit\u00e9 se structurera pour chacun des Livres blancs autour de deux phases :<br><br>1\/ Collecte des donn\u00e9es :<br>-Mettre en \u0153uvre un protocole de collecte et traitement de donn\u00e9es pour l&#8217;\u00e9laboration de livres blancs (enqu\u00eates par questionnaires \u00e9lectroniques et par entretiens) ;<br>-Organiser le traitement des donn\u00e9es et participer \u00e0 l&#8217;analyse des r\u00e9sultats ;<br>-Rassembler et archiver les contenus (questionnaires, textes, entretiens, etc.) ;<br><br>2\/ R\u00e9daction du Livre blanc :<br>-Coordonner la publication des livres blancs, en \u00e9troite collaboration avec les directions des GIS concern\u00e9s ;<br>-Assurer le suivi des contributeurs ;<br>-Effectuer la pr\u00e9paration de copie (normalisation, v\u00e9rification des contenus, structuration, relecture-correction), et \u00e9tablir les protocoles de relecture\/correction ; faire valider les diff\u00e9rentes \u00e9tapes de la r\u00e9alisation des Livres blancs par les auteurs ;<br>-R\u00e9aliser la mise en page, dans le respect de la charte graphique lorsqu&#8217;elle est d\u00e9j\u00e0 d\u00e9finie (GIS MOMM) ;<br>-Pr\u00e9parer les \u00e9l\u00e9ments graphiques de la publication et faire pr\u00e9parer tous les documents d&#8217;illustration en rapport avec le Livre blanc ;<br><br>-R\u00e9diger des rapports ;<br>-Echanger, par \u00e9crit ou par oral, avec les diff\u00e9rents interlocuteurs du projet ;<br>-Etablir et faire respecter les plannings de fabrication et les devis.<\/p>\n\n\n\n<h3>Comp\u00e9tences<\/h3>\n\n\n\n<p>-Piloter un projet<br>-Savoir \u00e9laborer les outils de collecte (questionnaires, entretiens)<br>-Savoir organiser un corpus de donn\u00e9es en vue de son exploitation<br>-Savoir produire des r\u00e9sultats et r\u00e9diger des rapports ou des documents<br>-Proposer des r\u00e9\u00e9critures de documents scientifiques<br>-Appliquer les normes, proc\u00e9dures et r\u00e8gles \u00e9ditoriales<br>-G\u00e9rer la cha\u00eene \u00e9ditoriale<br>-Utiliser les logiciels sp\u00e9cifiques \u00e0 l&#8217;activit\u00e9<br>-Elaborer une charte \u00e9ditoriale<br>-Elaborer un cahier des charges et g\u00e9rer un budget<br>-Travailler en \u00e9quipe<\/p>\n\n\n\n<h3>Contexte de travail<\/h3>\n\n\n\n<p>L&#8217;Unit\u00e9 CNRS \u00ab Etudes ar\u00e9ales \u00bb porte les trois Groupements d&#8217;Int\u00e9r\u00eat Scientifique (GIS) Asie, Etudes africaines, et Moyen-Orient et mondes musulmans (MOMM), ainsi que le consortium de l&#8217;IR* Huma-Num DISTAM (DIgital Studies Africa, Asia and Middle East). L&#8217;ensemble de ces r\u00e9seaux f\u00e9d\u00e8re plus de 40 \u00e9tablissements de l&#8217;ESR, et plus de 100 laboratoires en SHS. Localis\u00e9 sur le Campus Condorcet \u00e0 Aubervilliers (m\u00e9tro 12 Front Populaire), l&#8217;Unit\u00e9 est constitu\u00e9e d&#8217;une dizaine d&#8217;agents.<br>La\/Le charg\u00e9(e) d&#8217;enqu\u00eates et d&#8217;\u00e9dition travaillera en \u00e9troite collaboration avec les charg\u00e9es d&#8217;appui du pilotage et les directions du GIS Asie et du GIS MOMM, et sous la responsabilit\u00e9 de la responsable de la coop\u00e9ration internationale de l&#8217;Unit\u00e9. Les deux Livres blancs qu&#8217;elle\/il coordonnera sont des projets men\u00e9s dans le cadre d&#8217;un financement du Minist\u00e8re de l&#8217;Enseignement Sup\u00e9rieur et de la Recherche et les r\u00e9sultats sont attendus pour 2024.<br>Un maximum de deux jours de t\u00e9l\u00e9travail par semaine peut \u00eatre mis en place.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour postuler : https:\/\/emploi.cnrs.fr\/Offres\/CDD\/UAR2999-RICARO-002\/Default.aspx Date Limite Candidature : vendredi 21 juillet 2023 Assurez-vous que votre profil candidat soit correctement renseign\u00e9 avant de postuler. Les informations de votre profil compl\u00e8tent celles associ\u00e9es \u00e0 chaque candidature. Afin d\u2019augmenter votre visibilit\u00e9 sur notre Portail Emploi et ainsi permettre aux recruteurs de consulter votre profil candidat, vous avez la &#8230; <a title=\"Offre de CDD : Charg\u00e9-e d&#8217;enqu\u00eates et d&#8217;\u00e9dition de deux livres blancs en \u00e9tudes ar\u00e9ales (H\/F) &#8211; GIS Asie et GIS MOMM\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/2023\/07\/03\/offre-de-cdd-charge-e-denquetes-et-dedition-de-deux-livres-blancs-en-etudes-areales-h-f-gis-asie-et-gis-momm\/\">Read more<span class=\"screen-reader-text\">Offre de CDD : Charg\u00e9-e d&#8217;enqu\u00eates et d&#8217;\u00e9dition de deux livres blancs en \u00e9tudes ar\u00e9ales (H\/F) &#8211; GIS Asie et GIS MOMM<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,14,27],"tags":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/3019"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3019"}],"version-history":[{"count":1,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/3019\/revisions"}],"predecessor-version":[{"id":3020,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/3019\/revisions\/3020"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3019"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}