{"id":2792,"date":"2022-02-14T11:01:40","date_gmt":"2022-02-14T10:01:40","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?p=2792"},"modified":"2022-02-14T11:01:40","modified_gmt":"2022-02-14T10:01:40","slug":"afrase-association-francaise-pour-la-recherche-sur-lasie-du-sud-est-recrutement-coordinateur-rice-cdd-5-mois-euroseas","status":"publish","type":"post","link":"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/14\/afrase-association-francaise-pour-la-recherche-sur-lasie-du-sud-est-recrutement-coordinateur-rice-cdd-5-mois-euroseas\/","title":{"rendered":"AFRASE (Association fran\u00e7aise pour la recherche sur l\u2019Asie du Sud-Est) : Recrutement coordinateur-rice (CDD 5 mois) EUROSEAS"},"content":{"rendered":"\n<p>L\u2019<strong>Association fran\u00e7aise pour la recherche sur l\u2019Asie du Sud-Est<\/strong>\u00a0(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/afrase.hypotheses.org\/\">AFRASE<\/a>) rassemble des chercheur-es et des enseignant-es de toutes disciplines partageant un int\u00e9r\u00eat pour l\u2019Asie du Sud-Est.<strong>\u00a0Elle est la correspondante fran\u00e7aise de la European Association for Southeast Asian Studies (<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/www.euroseas.org\/event\/conference-2022\/\">EuroSEAS<\/a>), et organise \u00e0 ce titre le 12<sup>e<\/sup>\u00a0congr\u00e8s de l\u2019EuroSEAS du 28 juin au 1<sup>er<\/sup>\u00a0juillet 2022.<\/strong><br>Ce congr\u00e8s biennal rassemble plusieurs centaines de chercheur-es en sciences humaines et sociales venu-es du monde entier (entre 700 et 800 participant-es attendu-es). Cette ann\u00e9e,<strong>\u00a0il se tiendra \u00e0 l\u2019Ecole des Hautes Etudes en Sciences Sociales et sur le Campus Condorcet \u00e0 Aubervilliers,<\/strong>\u00a0grand p\u00f4le de recherche en sciences humaines et sociales.<br>Dans le cadre de ce congr\u00e8s,\u00a0<strong>l&#8217;AFRASE recrute un-e coordinateur-rice (contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e de 5 mois).<\/strong>\u00a0Plac\u00e9e sous l\u2019autorit\u00e9 hi\u00e9rarchique du comit\u00e9 d\u2019organisation du congr\u00e8s EuroSEAS 2022,\u00a0 cette personne aura notamment pour mission l\u2019organisation mat\u00e9rielle, logistique et administrative de ce congr\u00e8s europ\u00e9en et en\u00a0assurera la communication.\u00a0<br>Vous trouverez\u00a0<strong>toutes les informations sur le poste ainsi que pour la candidature dans le document joint.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2022\/02\/Fiche-de-poste-coordination-EuroSEAS-2022.pdf\">Fiche-de-poste-coordination-EuroSEAS-2022<\/a><a href=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2022\/02\/Fiche-de-poste-coordination-EuroSEAS-2022.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Association fran\u00e7aise pour la recherche sur l\u2019Asie du Sud-Est\u00a0(AFRASE) rassemble des chercheur-es et des enseignant-es de toutes disciplines partageant un int\u00e9r\u00eat pour l\u2019Asie du Sud-Est.\u00a0Elle est la correspondante fran\u00e7aise de la European Association for Southeast Asian Studies (EuroSEAS), et organise \u00e0 ce titre le 12e\u00a0congr\u00e8s de l\u2019EuroSEAS du 28 juin au 1er\u00a0juillet 2022.Ce congr\u00e8s biennal &#8230; <a title=\"AFRASE (Association fran\u00e7aise pour la recherche sur l\u2019Asie du Sud-Est) : Recrutement coordinateur-rice (CDD 5 mois) EUROSEAS\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/14\/afrase-association-francaise-pour-la-recherche-sur-lasie-du-sud-est-recrutement-coordinateur-rice-cdd-5-mois-euroseas\/\">Read more<span class=\"screen-reader-text\">AFRASE (Association fran\u00e7aise pour la recherche sur l\u2019Asie du Sud-Est) : Recrutement coordinateur-rice (CDD 5 mois) EUROSEAS<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,14,17,27],"tags":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2792"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2792"}],"version-history":[{"count":1,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2792\/revisions"}],"predecessor-version":[{"id":2794,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2792\/revisions\/2794"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2792"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}