{"id":2784,"date":"2022-02-11T14:27:21","date_gmt":"2022-02-11T13:27:21","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?p=2784"},"modified":"2022-02-11T14:27:21","modified_gmt":"2022-02-11T13:27:21","slug":"offre-de-stage-master-2-charge-e-de-recherche-junior-au-groupe-de-recherche-energie-technologie-et-societe-grets-dedf-rd","status":"publish","type":"post","link":"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/11\/offre-de-stage-master-2-charge-e-de-recherche-junior-au-groupe-de-recherche-energie-technologie-et-societe-grets-dedf-rd\/","title":{"rendered":"Offre de stage Master 2 : charg\u00e9-e de recherche junior au Groupe de Recherche Energie Technologie et Soci\u00e9t\u00e9 (GRETS) d\u2019EDF R&#038;D"},"content":{"rendered":"\n<p><strong>Proposition de stage : charg\u00e9-e de recherche junior au Groupe de Recherche Energie Technologie et Soci\u00e9t\u00e9 (GRETS) d\u2019EDF R&amp;D<\/strong><\/p>\n\n\n\n<p><strong>Objet : <\/strong>Analyse des communaut\u00e9s \u00e9nerg\u00e9tiques sur Tweeter.<\/p>\n\n\n\n<p><strong>Lieu : <\/strong>EDF R&amp;D, site EDF Lab de Saclay (Palaiseau)\u00a0+ possibilit\u00e9 de t\u00e9l\u00e9travail ponctuel<\/p>\n\n\n\n<p><strong>Indemnis\u00e9 : <\/strong>gratification de stage (1297\u20ac par mois\u00a0; 83,4% du smic brut mensuel) + 50% transports + acc\u00e8s cantine d\u2019entreprise<\/p>\n\n\n\n<p><strong>Dur\u00e9e : <\/strong>6 mois (second semestre, \u00e0 partir d\u2019avril 2022)<\/p>\n\n\n\n<p><strong>Profil recherch\u00e9 : <\/strong>master 2 en sciences politiques\/sociologie politique ou sociologie num\u00e9rique, avec un int\u00e9r\u00eat pour les humanit\u00e9s num\u00e9riques, les data sciences et\/ou l\u2019analyse de discours.<\/p>\n\n\n\n<p><strong>Candidature (CV+ lettre de motivation) \u00e0 adresser \u00e0 : <a rel=\"noreferrer noopener\" target=\"_blank\" href=\"mailto:mathieu.brugidou@edf.fr\">mathieu.brugidou@edf.fr<\/a> ou <a rel=\"noreferrer noopener\" target=\"_blank\" href=\"mailto:jeremy.bouillet@edf.fr\">jeremy.bouillet@edf.fr<\/a><\/strong><\/p>\n\n\n\n<p><strong>Description du stage :<\/strong><\/p>\n\n\n\n<p>Le GRETS est un groupe interdisciplinaire en sciences sociales qui r\u00e9alise des \u00e9tudes et des recherches au sein de la direction R&amp;D du groupe EDF. Le GRETS souhaite recruter un\/e stagiaire pour participer \u00e0 une recherche les d\u00e9bats sur les choix \u00e9nerg\u00e9tiques sur Twitter.<\/p>\n\n\n\n<p>Int\u00e9gr\u00e9 \u00e0 une \u00e9quipe pluridisciplinaire en sciences sociales et de data sciences d\u2019EDF R&amp;D et de Lyon II, le stagiaire contribuera \u00e0 l\u2019analyse d\u2019un corpus de tweets portant sur les questions \u00e9nerg\u00e9tiques dans la p\u00e9riode 2021 jusqu\u2019\u00e0 la fin du premier semestre 2022. Il s\u2019agit de s\u2019int\u00e9resser aux communaut\u00e9s qui peuvent exister sur Tweeter autour des enjeux \u00e9nerg\u00e9tiques, en questionnant leurs dynamiques lors des campagnes r\u00e9gionales et pr\u00e9sidentielles, et en cherchant \u00e0 d\u00e9terminer leur morphologie et leurs discours.<\/p>\n\n\n\n<p>Dans le cadre d\u2019une campagne d\u2019annotation des tweets, le stagiaire participera \u00e0 l\u2019\u00e9tablissement d\u2019une grille de codification, \u00e0 l\u2019annotation puis \u00e0 l\u2019analyse du corpus. Par ailleurs, le stagiaire participera \u00e0 un travail d\u2019exploration qualitative des communaut\u00e9s mises en \u00e9vidence par l\u2019\u00e9tude. Outre un travail d\u2019ethnographie num\u00e9rique, le stagiaire r\u00e9alisera des entretiens aupr\u00e8s de membres de ces communaut\u00e9s. En termes de sociologie politique, le stagiaire cherchera \u00e0 comprendre la place de ces communaut\u00e9s dans le d\u00e9bat public.<\/p>\n\n\n\n<p><strong>J\u00e9r\u00e9my BOUILLET<\/strong><br><strong>Ing\u00e9nieur-chercheur \/ PhD Science politique<\/strong><br>EDF Lab Paris-Saclay<br>Bureau 01FG22 &#8211; SEQUOIA \u2013 GRETS<br>7, boulevard Gaspard Monge<br>91120 Palaiseau<\/p>\n\n\n\n<p><strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"mailto:jeremy.bouillet@edf.fr\">jeremy.bouillet@edf.fr<\/a><\/strong><\/p>\n\n\n\n<p>T\u00e9l.&nbsp;: 01.78.19.43.40<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proposition de stage : charg\u00e9-e de recherche junior au Groupe de Recherche Energie Technologie et Soci\u00e9t\u00e9 (GRETS) d\u2019EDF R&amp;D Objet : Analyse des communaut\u00e9s \u00e9nerg\u00e9tiques sur Tweeter. Lieu : EDF R&amp;D, site EDF Lab de Saclay (Palaiseau)\u00a0+ possibilit\u00e9 de t\u00e9l\u00e9travail ponctuel Indemnis\u00e9 : gratification de stage (1297\u20ac par mois\u00a0; 83,4% du smic brut mensuel) + &#8230; <a title=\"Offre de stage Master 2 : charg\u00e9-e de recherche junior au Groupe de Recherche Energie Technologie et Soci\u00e9t\u00e9 (GRETS) d\u2019EDF R&#038;D\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/11\/offre-de-stage-master-2-charge-e-de-recherche-junior-au-groupe-de-recherche-energie-technologie-et-societe-grets-dedf-rd\/\">Read more<span class=\"screen-reader-text\">Offre de stage Master 2 : charg\u00e9-e de recherche junior au Groupe de Recherche Energie Technologie et Soci\u00e9t\u00e9 (GRETS) d\u2019EDF R&#038;D<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,27],"tags":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2784"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2784"}],"version-history":[{"count":1,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2784\/revisions"}],"predecessor-version":[{"id":2785,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2784\/revisions\/2785"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2784"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}