{"id":2770,"date":"2022-02-09T16:32:16","date_gmt":"2022-02-09T15:32:16","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?p=2770"},"modified":"2022-02-09T16:32:16","modified_gmt":"2022-02-09T15:32:16","slug":"offre-de-stage-master-1-ou-2-sociologie-numerique-et-sociabilites-agricoles","status":"publish","type":"post","link":"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/09\/offre-de-stage-master-1-ou-2-sociologie-numerique-et-sociabilites-agricoles\/","title":{"rendered":"Offre de stage Master 1 ou 2 Sociologie &#8211; Num\u00e9rique et Sociabilit\u00e9s agricoles"},"content":{"rendered":"\n<p>Vous trouverez ci-dessous une offre de stage recherche visant \u00e0 \u00e9tudier l\u2019\u00e9volution des sociabilit\u00e9s agricoles au regard du num\u00e9rique, \u00e0 l\u2019Ecole Nationale Sup\u00e9rieur d\u2019Agronomie de Toulouse. Ce stage s\u2019int\u00e8gre dans le projet de recherche PADAC, et se situe dans la continuit\u00e9 des recherches RESTIC men\u00e9es par M. Grossetti et G. Favre.<\/p>\n\n\n\n<p>Cette offre est \u00e0 destination d\u2019\u00e9tudiant.e.s de M1 ou M2 en sociologie ou \u00e9l\u00e8ve-ing\u00e9nieur.e en agronomie pour une p\u00e9riode allant de 3 \u00e0 6 mois. Vous trouverez plus de d\u00e9tails dans le document en pi\u00e8ce jointe.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a href=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2022\/02\/Offre-de-stage-2022-INP-ENSAT_Sociabilites_Agriculteurs_Numerique.pdf\">Offre-de-stage-2022-INP-ENSAT_Sociabilites_Agriculteurs_Numerique<\/a><a href=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2022\/02\/Offre-de-stage-2022-INP-ENSAT_Sociabilites_Agriculteurs_Numerique.pdf\" class=\"wp-block-file__button\" download>Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous trouverez ci-dessous une offre de stage recherche visant \u00e0 \u00e9tudier l\u2019\u00e9volution des sociabilit\u00e9s agricoles au regard du num\u00e9rique, \u00e0 l\u2019Ecole Nationale Sup\u00e9rieur d\u2019Agronomie de Toulouse. Ce stage s\u2019int\u00e8gre dans le projet de recherche PADAC, et se situe dans la continuit\u00e9 des recherches RESTIC men\u00e9es par M. Grossetti et G. Favre. Cette offre est \u00e0 &#8230; <a title=\"Offre de stage Master 1 ou 2 Sociologie &#8211; Num\u00e9rique et Sociabilit\u00e9s agricoles\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/2022\/02\/09\/offre-de-stage-master-1-ou-2-sociologie-numerique-et-sociabilites-agricoles\/\">Read more<span class=\"screen-reader-text\">Offre de stage Master 1 ou 2 Sociologie &#8211; Num\u00e9rique et Sociabilit\u00e9s agricoles<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,14,27,16],"tags":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2770"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":1,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2770\/revisions"}],"predecessor-version":[{"id":2772,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/2770\/revisions\/2772"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2770"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}