{"id":1037,"date":"2018-09-24T12:13:44","date_gmt":"2018-09-24T11:13:44","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?p=1037"},"modified":"2018-09-24T12:13:44","modified_gmt":"2018-09-24T11:13:44","slug":"lidhe-s-recrute-un-ingenieur-detudes-a-temps-partiel-quotite-50-sur-son-site-de-nanterre","status":"publish","type":"post","link":"http:\/\/amiens-sociologie.fr\/index.php\/2018\/09\/24\/lidhe-s-recrute-un-ingenieur-detudes-a-temps-partiel-quotite-50-sur-son-site-de-nanterre\/","title":{"rendered":"L\u2019IDHE.S recrute un ing\u00e9nieur d&#8217;\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre"},"content":{"rendered":"<p><a class=\"m_2789305949909425214moz-txt-link-freetext\" href=\"https:\/\/idhes.parisnanterre.fr\/actualites\/appel-a-canditatures-ingenieur-d-etudes-860264.kjsp?RH=comp_idhesem\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/idhes.parisnanterre.fr\/actualites\/appel-a-canditatures-ingenieur-d-etudes-860264.kjsp?RH%3Dcomp_idhesem&amp;source=gmail&amp;ust=1537873358119000&amp;usg=AFQjCNEVQ5nYreAHSCgOGHVeixNWlZqCqg\">https:\/\/idhes.parisnanterre.<wbr \/>fr\/actualites\/appel-a-<wbr \/>canditatures-ingenieur-d-<wbr \/>etudes-860264.kjsp?RH=comp_<wbr \/>idhesem<\/a><\/p>\n<div class=\"m_2789305949909425214actualite_cartouche\">\n<p id=\"m_2789305949909425214resume\"><b>L\u2019IDHE.S recrute un ing\u00e9nieur d&#8217;\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre.<\/b><\/p>\n<\/div>\n<div class=\"m_2789305949909425214liste-definitions\">\n<div class=\"m_2789305949909425214liste-definitions__terme--colonne\">Date(s)<\/div>\n<div class=\"m_2789305949909425214liste-definitions__definition--colonne\">\n<p id=\"m_2789305949909425214date\">du 10 septembre 2018 au 1 octobre 2018<\/p>\n<\/div>\n<\/div>\n<div id=\"m_2789305949909425214description\" class=\"m_2789305949909425214toolbox\">\n<div>En lien avec une recherche intitul\u00e9e \u00ab Emploi discontinu et indemnisation du ch\u00f4mage : quels usages des contrats courts ? \u00bb dans le cadre d\u2019une convention avec la direction de l\u2019animation de la recherche, des \u00e9tudes et des statistiques (DARES) du minist\u00e8re du travail, et en partenariat avec le Centre d\u2019\u00c9tudes du Travail et de l\u2019Emploi (CEET-CNAM), l\u2019IDHE.S recrute un ing\u00e9nieur d\u2019\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre. En \u00e9troite collaboration avec Mathieu Gr\u00e9goire et Claire Viv\u00e9s, les responsables de la recherche, la personne recrut\u00e9e participera \u00e0 la recherche et \u00e0 la r\u00e9daction du rapport.<\/div>\n<p><strong>Niveau requis<\/strong><br \/>\nPeuvent pr\u00e9senter leur candidature : les titulaires d\u2019une licence en \u00e9conomie, sociologie ou sciences sociales.<\/p>\n<p><strong>Qualit\u00e9s requises<\/strong><br \/>\nLa personne retenue devra avoir de bonnes qualit\u00e9s r\u00e9dactionnelles, une bonne ma\u00eetrise des m\u00e9thodes de recherche en sciences sociales.\u00a0En particulier, elle sera amen\u00e9e \u00e0 organiser et \u00e0 effectuer une campagne d\u2019entretiens sociologiques.<\/p>\n<p><strong>Dur\u00e9e du contrat<\/strong><\/p>\n<div>Le contrat propos\u00e9 est un contrat \u00e0 temps partiel d\u2019une dur\u00e9e de 8 mois \u00e0 partir du 1er novembre 2018.<br \/>\nIl implique une pr\u00e9sence \u00e0 l\u2019IDHE.S Nanterre durant toute la p\u00e9riode du contrat. La r\u00e9mun\u00e9ration pr\u00e9vue correspond \u00e0 la grille des \u00ab Ing\u00e9nieurs d\u2019\u00e9tudes en production, traitement, analyse de donn\u00e9es et enqu\u00eates &#8211; D2A41 \u00bb BAP D soit environ 900 euros net pour un mi-temps.\u00a0<a class=\"m_2789305949909425214lien_externe\" href=\"https:\/\/data.enseignementsup-recherche.gouv.fr\/pages\/fiche_emploi_type_referens_iii_itrf\/?refine.referens_id=D2A41#top\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/data.enseignementsup-recherche.gouv.fr\/pages\/fiche_emploi_type_referens_iii_itrf\/?refine.referens_id%3DD2A41%23top&amp;source=gmail&amp;ust=1537873358119000&amp;usg=AFQjCNEKKXJW1_EP5i4j7bZzqDjROJf9BA\">https:\/\/data.enseignementsup-<wbr \/>recherche.gouv.fr\/pages\/fiche_<wbr \/>emploi_type_referens_iii_itrf\/<wbr \/>?refine.referens_id=D2A41#top<\/a><\/div>\n<p><strong>Pr\u00e9sentation de la recherche<\/strong><\/p>\n<div>La convention porte sur les usages des CDD de moins d\u2019un mois en lien (ou non) avec les r\u00e8gles de l\u2019assurance ch\u00f4mage relatives \u00e0 \u00ab l\u2019activit\u00e9 r\u00e9duite \u00bb.<\/p>\n<p>Si la proportion d\u2019emploi \u00e0 CDD a peu \u00e9volu\u00e9 dans les derni\u00e8res ann\u00e9es, on observe en revanche que ceux-ci sont de plus en plus courts : le nombre de CDD de moins d\u2019un mois a connu un essor tr\u00e8s important dans les derni\u00e8res ann\u00e9es. Depuis 2000, le nombre d\u2019embauches en CDD de moins d\u2019un mois a progress\u00e9 de 161 % et celui en int\u00e9rim de 32 % alors que sur la m\u00eame p\u00e9riode, le nombre d\u2019embauches en CDI ou CDD de plus d\u2019un mois n\u2019a progress\u00e9 que de 15%. Selon une hypoth\u00e8se largement reprise, cette augmentation des contrats courts serait favoris\u00e9e par des strat\u00e9gies opportunistes des employeurs, comme des salari\u00e9s, visant \u00e0 maximiser le recours \u00e0 l\u2019assurance ch\u00f4mage tout en minimisant les dur\u00e9es d\u2019emploi et les co\u00fbts salariaux. La solvabilisation par l\u2019indemnisation ch\u00f4mage de ces situations d\u2019emploi fragment\u00e9 aboutirait, d\u2019un point de vue individuel, \u00e0 un maintien durable dans une alternance emploi-ch\u00f4mage et, d\u2019un point de vue collectif, \u00e0 la croissance du nombre de ces salari\u00e9s pr\u00e9caires ainsi qu\u2019\u00e0 une fuite en avant des d\u00e9penses de l\u2019assurance ch\u00f4mage.<\/p><\/div>\n<div>La pr\u00e9sente recherche vise \u00e0 tester cette hypoth\u00e8se sociologiquement. Elle comprend pour cela plusieurs volets :<\/div>\n<div>&#8211; un cadrage quantitatif visant \u00e0 compl\u00e9ter les connaissances actuelles sur les trajectoires d\u2019emploi et de ch\u00f4mage des salari\u00e9s ayant eu un ou plusieurs contrats de courte dur\u00e9e ainsi que sur les entreprises qui les emploient ;<br \/>\n&#8211; un cadrage qualitatif appuy\u00e9 sur deux journ\u00e9es d\u2019\u00e9tudes permettant d\u2019interroger le caract\u00e8re sp\u00e9cifique ou non de l\u2019usage de contrats courts dans les secteurs qui y ont le plus recours ;<br \/>\n&#8211; une analyse de terrain centr\u00e9e sur des salari\u00e9s\/ch\u00f4meurs ayant eu un ou plusieurs contrats courts visant \u00e0 mieux \u00e9clairer les pratiques objectives mais aussi le v\u00e9cu subjectif associ\u00e9 d\u2019une part \u00e0 ces emplois courts et\/ou fragment\u00e9s et d\u2019autre part aux p\u00e9riodes de ch\u00f4mage interstitielles entre ces contrats ;<br \/>\n&#8211; une \u00e9tude des usages des employeurs par le prisme indirect d\u2019une analyse des n\u00e9gociations de branche relatives \u00e0 l\u2019usage des contrats courts pr\u00e9vues par la convention d\u2019assurance ch\u00f4mage de f\u00e9vrier 2018.<\/div>\n<div>\nLa personne recrut\u00e9e sera amen\u00e9e \u00e0 travailler la partie \u00ab analyse de terrain \u00bb dont l\u2019objectif est de partir des exp\u00e9riences singuli\u00e8res de l\u2019emploi et du ch\u00f4mage d\u2019un point de vue objectif (quelles sont les pratiques ?) et d\u2019un point de vue subjectif (quel est le \u00ab v\u00e9cu \u00bb associ\u00e9 \u00e0 ces situations ? quelles sont les aspirations de ces salari\u00e9s ? quelle est leur appr\u00e9ciation, positive ou n\u00e9gative, de leur situation ?).<\/p>\n<p>Les enqu\u00eates porteront sur trois territoires : les Alpes-Maritimes, le Val d\u2019Oise et la Somme. Certains secteurs seront plus particuli\u00e8rement cibl\u00e9s : le secteur de l\u2019h\u00e9bergement m\u00e9dico-social (en particulier les maisons de retraite), le secteur de l\u2019h\u00f4tellerie restauration le secteur du transport (en particulier le d\u00e9m\u00e9nagement et le secteur de l\u2019agroalimentaire). La personne recrut\u00e9e devra prendre en charge une partie de la campagne d\u2019entretiens dans la Somme ou dans le Val d\u2019Oise.<\/p><\/div>\n<p><strong>Pr\u00e9sentation du laboratoire<\/strong><\/p>\n<div>L\u2019IDHE.S, Institutions et Dynamiques Historiques de l\u2019Economie et de la Soci\u00e9t\u00e9, est une Unit\u00e9 Mixte de Recherche (UMR 8533) cr\u00e9\u00e9e en 1997 entre le CNRS et des partenaires universitaires, en regroupant les apports de l\u2019Institut d\u2019Histoire \u00c9conomique et Sociale (IHES) fond\u00e9 par Ernest Labrousse, du Centre d\u2019\u00c9tude des Croissances fond\u00e9 Maurice L\u00e9vy-Leboyer et ceux du GDR \u00ab Institutions Emploi et Politiques \u00c9conomiques \u00bb fond\u00e9 par Robert Salais.<\/p>\n<p>Depuis, l\u2019IDHE.S a int\u00e9gr\u00e9 des sociologues venant de diff\u00e9rents horizons, ce qui en a fait un laboratoire v\u00e9ritablement interdisciplinaire. L\u2019arriv\u00e9e en janvier 2011 du Laboratoire Georges Friedmann (LGF) de Paris Panth\u00e9on-Sorbonne et celle du Laboratoire d\u2019Histoire \u00c9conomique, Sociale et des Techniques (LHEST) de l\u2019Universit\u00e9 d\u2019\u00c9vry-Val d\u2019Essonne en janvier 2013 ont compl\u00e9t\u00e9 cette dynamique. L\u2019IDHE.S compte aujourd\u2019hui 60 membres permanents et 100 doctorants.<\/p>\n<p>Le projet scientifique de l\u2019IDHE.S se concentre sur la dynamique historique des institutions de l\u2019\u00e9conomie. Il mobilise les quatre disciplines que sont le droit, l\u2019\u00e9conomie, l\u2019histoire et la sociologie.<\/p><\/div>\n<p><strong>Modalit\u00e9s de soumission de la candidature<\/strong><\/p>\n<div>Les candidats doivent adresser une lettre de motivation accompagn\u00e9e d\u2019un curriculum vitae avant le\u00a0<strong>1er octobre 2018<\/strong>\u00a0sous forme \u00e9lectronique \u00e0 Mathieu Gr\u00e9goire et Claire Viv\u00e9s :\u00a0<a class=\"m_2789305949909425214lien_externe\" href=\"mailto:mgregoire@parisnanterre.fr?subject=Candidature%20%3A%20ing%C3%A9nieur%20d%27%C3%A9tudes\" target=\"_blank\" rel=\"noopener\">mgregoire@parisnanterre.fr<\/a>\u00a0;\u00a0<a class=\"m_2789305949909425214lien_externe\" href=\"mailto:claire.vives@lecnam.net\" target=\"_blank\" rel=\"noopener\">claire.vives@lecnam.net<\/a>.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/idhes.parisnanterre.fr\/actualites\/appel-a-canditatures-ingenieur-d-etudes-860264.kjsp?RH=comp_idhesem L\u2019IDHE.S recrute un ing\u00e9nieur d&#8217;\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre. Date(s) du 10 septembre 2018 au 1 octobre 2018 En lien avec une recherche intitul\u00e9e \u00ab Emploi discontinu et indemnisation du ch\u00f4mage : quels usages des contrats courts ? \u00bb dans le cadre d\u2019une convention avec la direction &#8230; <a title=\"L\u2019IDHE.S recrute un ing\u00e9nieur d&#8217;\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/2018\/09\/24\/lidhe-s-recrute-un-ingenieur-detudes-a-temps-partiel-quotite-50-sur-son-site-de-nanterre\/\">Read more<span class=\"screen-reader-text\">L\u2019IDHE.S recrute un ing\u00e9nieur d&#8217;\u00e9tudes \u00e0 temps partiel (quotit\u00e9 : 50%) sur son site de Nanterre<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,27],"tags":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1037"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":1,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1037\/revisions"}],"predecessor-version":[{"id":1038,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1037\/revisions\/1038"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1037"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}