{"id":276,"date":"2017-10-10T08:29:41","date_gmt":"2017-10-10T07:29:41","guid":{"rendered":"http:\/\/amiens-sociologie.fr\/?page_id=276"},"modified":"2023-09-05T15:33:33","modified_gmt":"2023-09-05T14:33:33","slug":"sociologie-politique-cm-et-td-l2s3-et-l3s5","status":"publish","type":"page","link":"http:\/\/amiens-sociologie.fr\/index.php\/sociologie-politique-cm-et-td-l2s3-et-l3s5\/","title":{"rendered":"Sociologie politique (CM L2S3)"},"content":{"rendered":"<p><strong>Cours d\u2019Isabelle CHARPENTIER<\/strong><\/p>\n<p><strong>icharpentier@yahoo.fr ou isabelle.charpentier@u-picardie.fr<br \/>\n<\/strong><\/p>\n<p><strong>L2S3 \u2013 UE Disciplinaire Compl\u00e9mentaire Sociologie <\/strong><strong>; CM optionnel de 24 h \u2013 3 ects<\/strong><\/p>\n<h1 style=\"text-align: center;\"><strong>SOCIOLOGIE POLITIQUE<\/strong><\/h1>\n<p><img loading=\"lazy\" class=\"size-full wp-image-371 aligncenter\" src=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2017\/10\/Vote-2.png\" alt=\"\" width=\"221\" height=\"228\" \/><\/p>\n<p><strong><u>R\u00e9sum\u00e9<\/u><\/strong><\/p>\n<p>L\u2019organisation politique des soci\u00e9t\u00e9s contemporaines pr\u00e9sente trois caract\u00e9ristiques principales : elle repose sur une diff\u00e9renciation du politique des autres activit\u00e9s sociales, elle est de type \u00e9tatique et elle est comp\u00e9titive. Cette organisation, toute comme sa traduction concr\u00e8te contemporaine, la d\u00e9mocratie repr\u00e9sentative parlementaire, appara\u00eet aujourd\u2019hui comme \u00ab naturelle \u00bb et semble former un horizon ind\u00e9passable. Pourtant, cette organisation politique et la mise en place des institutions repr\u00e9sentatives n\u2019ont pas \u00e9t\u00e9 de soi d\u2019un point de vue historique : depuis l\u2019Antiquit\u00e9, elles r\u00e9sultent d\u2019un processus multis\u00e9culaire de construction et ont n\u00e9cessit\u00e9 de longs et nombreux combats. L\u2019objet de ce CM\/TD (assiduit\u00e9 obligatoire), construit dans une perspective de sociologie historique, est notamment de faire comprendre la place de l\u2019acte \u00e9lectoral dans les d\u00e9mocraties pluralistes, au-del\u00e0 de la fonction explicite de d\u00e9signer les repr\u00e9sentants. D\u2019o\u00f9 provient le type de relation qu\u2019entretient le citoyen au vote, quelles sont les significations possibles de l\u2019acte \u00e9lectoral au regard du processus de naissance de la citoyennet\u00e9 et de cons\u00e9cration du suffrage universel ? Comment ont \u00e9t\u00e9 invent\u00e9es et comment se sont progressivement transform\u00e9es les r\u00e8gles du jeu \u00e9lectoral ? La citoyennet\u00e9 appara\u00eet ainsi comme le fruit d\u2019un long travail d\u2019apprentissage dont l\u2019enjeu sera d\u2019inventer le citoyen \u00e9lecteur, et d\u2019affirmer son r\u00f4le dans le mouvement vers la d\u00e9mocratie. Le cours reviendra ensuite sur les ressorts sociologiques de la participation politique (comp\u00e9tence politique, \u00ab cens cach\u00e9 \u00bb, socialisation politique, \u00ab volatilit\u00e9 \u00e9lectorale \u00bb), mais aussi de la non participation (non inscription, abstention intermittente ou syst\u00e9matique, votes blancs et nuls), de plus en plus fr\u00e9quente et nombreuse, en vue de mieux comprendre les rapports \u00ab ordinaires \u00bb au politique en d\u00e9mocratie repr\u00e9sentative.<\/p>\n<p><span style=\"color: #800080;\"><strong>Bibliographie succincte :<\/strong><\/span><\/p>\n<p>Braconnier (C\u00e9cile), Dormagen (Jean-Yves), <i>La D\u00e9mocratie de l\u2019abstention<\/i>, Paris, Folio Gallimard, 2007. Elias (Norbert), <i>La Dynamique de l\u2019Occident<\/i>, Paris, Presses Pocket, 1990 [e.o. 1939]. Finley (Moses), <i>D\u00e9mocratie antique, d\u00e9mocratie moderne<\/i>, Paris, Payot, 2003. Gaxie (Daniel), <i>La D\u00e9mocratie repr\u00e9sentative<\/i>, Paris, Montchrestien, 3\u00e8me \u00e9d. 2000. Gaxie (Daniel),<i> Le Cens cach\u00e9<\/i>, Paris, Seuil, 1978.<\/p>\n<p><strong><u>Modalit\u00e9s de contr\u00f4le des connaissances<br \/>\n<\/u><\/strong><\/p>\n<p><strong>Examen Terminal Ecrit (ETE) de 2 heures (1<sup>\u00e8re<\/sup> session et session de rattrapage).<\/strong> Une attention particuli\u00e8re sera accord\u00e9e \u00e0 la rigueur dans la d\u00e9finition des concepts, et\u2026 \u00e0 la qualit\u00e9 de l\u2019orthographe, de la syntaxe et de la ponctuation. Aucun document ne sera autoris\u00e9.<\/p>\n<h2 style=\"text-align: center;\"><strong><u>PLAN DE COURS &amp; BIBLIOGRAPHIES<\/u><\/strong><\/h2>\n<h3><strong><u>INTRODUCTION\u00a0:<\/u><\/strong><strong> L\u2019organisation politique des soci\u00e9t\u00e9s contemporaines &#8211; <\/strong><strong>Quelques d\u00e9finitions pr\u00e9alables<\/strong><\/h3>\n<p>Sociologie politique ; les trois sens du mot \u00ab politique \u00bb : <em>polity<\/em>, <em>politics<\/em>, <em>policies\u00a0; <\/em>domination &amp; l\u00e9gitimit\u00e9 (Max Weber)\u00a0; pouvoir (Max Weber) ; \u00ab\u00a0comp\u00e9tition politique\u00a0\u00bb\u00a0; \u00ab\u00a0professionnel de la politique\u00a0\u00bb\u00a0; \u00ab\u00a0troph\u00e9e politique\u00a0\u00bb\u00a0; \u00ab\u00a0enjeu politique\u00a0\u00bb\u00a0; \u00ab\u00a0champ politique\u00a0\u00bb (central ou national, p\u00e9riph\u00e9rique int\u00e9gr\u00e9, p\u00e9riph\u00e9rique)\u00a0; \u00ab\u00a0march\u00e9 politique\u00a0\u00bb\u00a0; \u00ab\u00a0comp\u00e9tence politique\u00a0\u00bb\u00a0; \u00ab\u00a0politisation\u00a0\u00bb\u00a0; \u00ab\u00a0profanes\u00a0\u00bb.<\/p>\n<p><strong><u><span style=\"color: #800080;\">Bibliographie pour l\u2019introduction &amp; ouvrages g\u00e9n\u00e9raux (manuels et synth\u00e8ses)<\/span><br \/>\n<\/u><\/strong><\/p>\n<p>&#8211; Baudot (Pierre-Yves), Rib\u00e9mont (Thomas) [dir.], <em>Science politique<\/em>, Paris, Foucher, coll. \u00ab\u00a0LMD\u00a0\u00bb, 2010.<\/p>\n<p>&#8211; Cohen (Antonin), Lacroix (Bernard), Riutort (Philippe) [dir.], <em>Nouveau manuel de science politique<\/em>, Paris, La D\u00e9couverte, coll. \u00ab\u00a0Manuels Grands Rep\u00e8res\u00a0\u00bb, 2009.<\/p>\n<p>&#8211; D\u00e9loye (Yves), Voutat (Bernard) [dir.], <em>Faire de la science politique. Pour une analyse sociohistorique du politique<\/em>, Paris, Belin, 2002.<\/p>\n<p>&#8211; Dormagen (Jean-Yves), Mouchard (Daniel), <em>Introduction \u00e0 la sociologie politique<\/em>, De Boeck, 2015 (4\u00e8me \u00e9d.).<\/p>\n<p>&#8211; Dulong (Delphine), <em>La Construction du champ politique<\/em>, Rennes, PUR, 2010.<\/p>\n<p>&#8211; Gaxie (Daniel), \u00ab\u00a0Sur quelques concepts fondamentaux de la science politique\u00a0\u00bb, in <em>Droit, institutions et syst\u00e8mes politiques \u2013 M\u00e9langes en hommage \u00e0 Maurice Duverger<\/em>, Paris, PUF, 1987, pp. 569-612.<\/p>\n<p>&#8211; Goujon (Alexandra), <em>Les D\u00e9mocraties. Institutions, fonctionnement et d\u00e9fis<\/em>, Paris, Armand Colin, 2015.<\/p>\n<p>&#8211; Holeindre (Jean-Vincent) [dir.], <em>Le Pouvoir.<\/em> <em>Concepts, Lieux, Dynamiques<\/em>, Paris, \u00e9d. Sciences Humaines, 2014.<\/p>\n<p>&#8211; Lagroye (Jacques), Fran\u00e7ois (Bastien), Sawicki (Fr\u00e9d\u00e9ric), <em>Sociologie politique<\/em>, Paris, Montchrestien, 2002 [4<sup>\u00e8me<\/sup> \u00e9d.].<\/p>\n<p>&#8211; <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/lectures.revues.org\/9491\">Lambert<\/a><\/span> (Fr\u00e9d\u00e9ric), <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/lectures.revues.org\/2663\">Lefranc<\/a><\/span> (Sandrine), <em>50 fiches pour comprendre la science politique<\/em>, Paris, Br\u00e9al, coll. \u00ab\u00a050 fiches\u00a0\u00bb, 2012.<\/p>\n<p>&#8211; Lefebvre (R\u00e9mi), <em>Le\u00e7ons d\u2019introduction \u00e0 la science politique<\/em>, Paris, Editions Ellipses, 2<sup>e<\/sup> \u00e9d. 2013.<\/p>\n<p>&#8211; Van Campenhoudt (Luc), <em>Introduction \u00e0 l\u2019analyse des ph\u00e9nom\u00e8nes sociaux<\/em>, Paris, Dunod, 2001.<\/p>\n<p>&#8211; Voilliot (Christophe), <span style=\"color: #000000;\"><em><a style=\"color: #000000;\" href=\"http:\/\/www.liens-socio.org\/Elements-de-Science-politique\">El\u00e9ments de science politique<\/a><\/em><\/span>, Paris, L\u2019Harmattan, coll. \u00ab\u00a0Logiques politiques\u00a0\u00bb, 2010.<\/p>\n<h3 style=\"text-align: center;\"><strong><u>CHAPITRE 1. Une organisation politique diff\u00e9renci\u00e9e<\/u><\/strong><\/h3>\n<p><span style=\"color: #ff6600;\">Pour commencer, un petit quizz sur la citoyennet\u00e9 et la d\u00e9mocratie directe dans la Gr\u00e8ce antique&#8230;<\/span><\/p>\n<p><strong>Section 1. La d\u00e9mocratie ath\u00e9nienne\u00a0<\/strong><strong>: une soci\u00e9t\u00e9 \u00e0 organisation politique indiff\u00e9renci\u00e9e (Moses Finley)<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Section 2. D\u00e9mocratie antique, d\u00e9mocratie moderne\u00a0: diff\u00e9renciation, bureaucratisation, professionnalisation, s\u00e9cularisation<\/strong><\/p>\n<p><span style=\"color: #339966;\"><strong>Ouverture : vous visionnerez la vid\u00e9o suivante : &#8220;La d\u00e9mocratie ath\u00e9nienne&#8221;<\/strong> (9&#8217;32), consultable ici : https:\/\/www.youtube.com\/watch?v=tgKH_5n9xmg<\/span><\/p>\n<p><strong><span style=\"color: #ff6600;\">Annexe : Les institutions de la d\u00e9mocratie ath\u00e9nienne<\/span><\/strong><\/p>\n<p><img loading=\"lazy\" class=\"wp-image-2164 aligncenter\" src=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2020\/08\/democratie-ep2-2-schema-institu-300x300.jpg\" alt=\"\" width=\"359\" height=\"359\" srcset=\"http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2020\/08\/democratie-ep2-2-schema-institu-300x300.jpg 300w, http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2020\/08\/democratie-ep2-2-schema-institu-150x150.jpg 150w, http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2020\/08\/democratie-ep2-2-schema-institu-768x768.jpg 768w, http:\/\/amiens-sociologie.fr\/wp-content\/uploads\/2020\/08\/democratie-ep2-2-schema-institu.jpg 800w\" sizes=\"(max-width: 359px) 100vw, 359px\" \/><\/p>\n<p><span style=\"color: #800080;\"><strong><u>Bibliographie pour le chapitre 1<\/u><\/strong><\/span><\/p>\n<p>&#8211; Finley (Moses), <em>D\u00e9mocratie antique et d\u00e9mocratie moderne<\/em>, Paris, Petite Biblioth\u00e8que Payot, 1990.<\/p>\n<p>&#8211; Finley (Moses), <em>L\u2019Invention de la politique &#8211; D\u00e9mocratie et politique en Gr\u00e8ce et dans la Rome r\u00e9publicaine<\/em>, Paris, Flammarion, coll. \u00ab\u00a0Champs\u00a0\u00bb, 1985.<\/p>\n<p>&#8211; Gaxie (Daniel), <em>La D\u00e9mocratie repr\u00e9sentative<\/em>, Paris, Montchrestien, coll. \u00ab\u00a0Clefs Politique\u00a0\u00bb, 3\u00e8me \u00e9d. 2000.<\/p>\n<p><em>&#8211; Savoir\/agir<\/em>, n\u00b0 31, mars 2015\u00a0: \u00ab\u00a0La d\u00e9mocratie\u00a0\u00bb.<\/p>\n<h3 style=\"text-align: center;\"><strong><u>CHAPITRE 2. Une organisation politique de type \u00e9tatique<\/u><\/strong><\/h3>\n<p><strong>Introduction. Des soci\u00e9t\u00e9s sans Etat\u00a0? Les apports de l\u2019anthropologie politique (Pierre Clastres, Jean-William Lapierre, Edward E. Evans-Pritchard)<\/strong><\/p>\n<p><strong>Section 1. Emergence &amp; construction de l\u2019Etat moderne du Moyen Age \u00e0 la monarchie absolue<\/strong><\/p>\n<ul>\n<li><strong>1.<\/strong> L\u2019approche weberienne\u00a0: construction de l\u2019Etat &amp; monopolisation de la violence physique l\u00e9gitime<\/li>\n<li><strong>2.<\/strong> <em>La Dynamique de l\u2019Occident<\/em> &amp; la formation des \u00ab\u00a0monopoles-cl\u00e9s\u00a0\u00bb en Europe occidentale (Norbert Elias)\u00a0: historiciser les structures sociales<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>La formation des Etats modernes en Europe occidentale\u00a0: monopolisation &amp; interd\u00e9pendance<\/li>\n<li>&#8220;Curialisation des guerriers&#8221; et autocontr\u00f4le des pulsions<\/li>\n<li>La notion de configuration<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><span style=\"color: #339966;\"><strong>Ouverture : vous visionnerez le document suivant : &#8220;L&#8217;affirmation de l&#8217;Etat monarchique en France XI-XV\u00e8me si\u00e8cles&#8221;<\/strong> (14&#8217;06)<strong>, <\/strong>consultable ici :<\/span><\/p>\n<p><span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/www.youtube.com\/watch?v=7c6DVhPZFYs\">https:\/\/www.youtube.com\/watch?v=7c6DVhPZFYs<\/a><\/span><\/p>\n<p><strong><span style=\"color: #339966;\">Exercice propos\u00e9 : s<\/span><\/strong><span style=\"color: #339966;\"><strong>ur la base des analyses d\u00e9velopp\u00e9es par Norbert Elias, vous commenterez l\u2019extrait suivant :<\/strong><\/span><\/p>\n<p><span style=\"color: #339966;\">\u00ab\u00a0L\u2019existence de l\u2019Etat fa\u00e7onne [\u2026] de nouvelles formes de rapports sociaux\u00a0: la monarchie absolue cr\u00e9e, non sans r\u00e9sistances, une noblesse de cour sur la base d\u2019une noblesse f\u00e9odale asservie, nouvelle noblesse en un sens puisque ses revenus ne sont plus identiques \u00e0 ceux de la pr\u00e9c\u00e9dente (le service du roi \u00e9tant source de profits importants, \u00e0 c\u00f4t\u00e9 des revenus de ses terres), puisque ses comportements et ses ambitions sont transform\u00e9s par la vie de cour et puisque ses rapports aux bourgeois se trouvent modifi\u00e9s\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #339966;\">LAGROYE (Jacques), FRANCOIS (Bastien), SAWICKI (Fr\u00e9d\u00e9ric), <em>Sociologie politique<\/em>, Paris, Presses de Sciences Po &amp; Dalloz, 2002 [4<sup>\u00e8me<\/sup> \u00e9d.], p. 81.<\/span><\/p>\n<p><strong>Section 2. Les effets de la construction de l\u2019Etat<\/strong><\/p>\n<ul>\n<li><strong> 1.<\/strong> La transformation de la comp\u00e9tition politique<\/li>\n<li><strong>2.<\/strong> La bureaucratisation du monde (Max Weber)<\/li>\n<li><strong>3<\/strong>. L\u2019abaissement du seuil de tol\u00e9rance \u00e0 la violence<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Violence &amp; sport (Norbert Elias)<\/li>\n<li>Violence &amp; syst\u00e8me p\u00e9nal (Michel Foucault)<\/li>\n<li>Violence &amp; mouvements sociaux (Charles Tilly)<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<ul>\n<li><strong>4.<\/strong> La construction politique du sentiment national (Maurice Agulhon, Yves D\u00e9loye, Olivier Ihl, Mona &amp; Jacques Ozouf\u2026)<\/li>\n<li><strong>5.<\/strong> L\u2019int\u00e9gration politique du territoire &amp; de la population<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>L\u2019intervention croissante de l\u2019Etat<\/li>\n<li>Uniformisation, rationalisation &amp; politisation du monde social<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><span style=\"color: #800080;\"><strong><u>Bibliographie pour le chapitre 2\u00a0<\/u><\/strong><\/span><\/p>\n<p>&#8211; Agulhon (Maurice) [dir.], <em>Cultures et folklores r\u00e9publicains<\/em>, Paris, Editions du Comit\u00e9 des Travaux Historiques et Scientifiques, 1995.<\/p>\n<p>&#8211; Agulhon (Maurice), <em>La R\u00e9publique au village<\/em>, Paris, Plon, 1970.<\/p>\n<p>&#8211; Agulhon (Maurice), <em>Les M\u00e9tamorphoses de Marianne. L\u2019imagerie et la symbolique r\u00e9publicaines de 1914 \u00e0 nos jours<\/em>, Paris, Flammarion, 2001.<\/p>\n<p>&#8211; Agulhon (Maurice), <em>Marianne au combat. L\u2019imagerie et la symbolique r\u00e9publicaine de 1789 \u00e0 1880<\/em>, Paris, Flammarion, 1989.<\/p>\n<p>&#8211; Agulhon (Maurice), <em>Marianne au pouvoir. L\u2019imagerie et la symbolique r\u00e9publicaines de 1880 \u00e0 1914<\/em>, Paris, Flammarion, 1989.<\/p>\n<p>&#8211; D\u00e9loye (Yves), <em>Ecole et citoyennet\u00e9. L\u2019individualisme r\u00e9publicain de Jules Ferry \u00e0 Vichy\u00a0: controverses,<\/em> Paris, Presses de Science Po, 1994.<\/p>\n<p>&#8211; D\u00e9loye (Yves), <em>Sociologie historique du politique<\/em>, Paris, La D\u00e9couverte, coll. \u00ab\u00a0Rep\u00e8res\u00a0\u00bb, 2007.<\/p>\n<p>&#8211; Elias (Norbert), Dunning (Eric), <em>Sport et civilisation \u2013 La violence ma\u00eetris\u00e9e<\/em>, Paris, Fayard, 1994.<\/p>\n<p>&#8211; Elias (Norbert), <em>La Civilisation des m\u0153urs<\/em>, Paris, Hachette, Presses Pocket, 1989 [e.o. 1939].<\/p>\n<p>&#8211; Elias (Norbert), <em>La Dynamique de l\u2019Occident<\/em>, Paris, Presses Pocket, 1990 [e.o. 1939].<\/p>\n<p>&#8211; Elias (Norbert), <em>La Soci\u00e9t\u00e9 de cour<\/em>, Paris, Flammarion, coll. \u00ab\u00a0Champs\u00a0\u00bb, 1985 [e.o. 1969].<\/p>\n<p>&#8211; Foucault (Michel), <em>Surveiller et punir. Naissance de la prison<\/em>, Paris, Gallimard, 1975.<\/p>\n<p>&#8211; Garrigou (Alain), Lacroix (Bernard) [dir.], <em>Norbert Elias, la politique et l\u2019histoire<\/em>, Paris, La D\u00e9couverte, 1997.<\/p>\n<p>&#8211; Gaxie (Daniel), <em>La D\u00e9mocratie repr\u00e9sentative<\/em>, Paris, Montchrestien, coll. \u00ab\u00a0Clefs Politique\u00a0\u00bb, 3\u00e8me \u00e9d. 2000.<\/p>\n<p>&#8211; Guibert (Jo\u00ebl), Jumel (Guy), <em>La Socio-histoire<\/em>, Paris, Armand Colin coll. \u00ab\u00a0Cursus Sociologie\u00a0\u00bb, 2002.<\/p>\n<p>&#8211; <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Nathalie_Heinich\">Heinich<\/a><\/span> (Nathalie), <em>La Sociologie de <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Norbert_Elias\">Norbert Elias<\/a><\/span><\/em><span style=\"color: #000000;\">,<\/span> Paris, La D\u00e9couverte, 2002.<\/p>\n<p>&#8211; <span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"http:\/\/fr.wikipedia.org\/wiki\/Nathalie_Heinich\">Heinich<\/a><\/span> (Nathalie), <em>Dans la pens\u00e9e de Norbert Elias<\/em>, Paris, CNRS Edition, 2015<span style=\"color: #000000;\">.<\/span><\/p>\n<p>&#8211; Ihl (Olivier), <em>La F\u00eate r\u00e9publicaine<\/em>, Paris, Gallimard, 1996.<\/p>\n<p>&#8211; Noiriel (G\u00e9rard), <em>Introduction \u00e0 la socio-histoire<\/em>, Paris, La D\u00e9couverte, coll \u00ab\u00a0Rep\u00e8res\u00a0\u00bb, 2006.<\/p>\n<p>&#8211; Ozouf (Mona), Ozouf (Jacques), <em>La R\u00e9publique des instituteurs, <\/em>Paris, Seuil, coll. \u00ab\u00a0Point Histoire\u00a0\u00bb, 2001.<\/p>\n<p>&#8211; Passini (Michela), <em>La Fabrique de l\u2019art national. Le nationalisme et les origines de l\u2019histoire de l\u2019art en France et en Allemagne (1870-1933)<\/em>, Paris, Editions de la MSH, 2013.<\/p>\n<p>&#8211; Weber (Max), <em>Economie et soci\u00e9t\u00e9<\/em>, Paris, Plon, coll. \u00ab\u00a0Agora\u00a0\u00bb, 1995 [e.o. 1921].<\/p>\n<p>&#8211; Weber (Max), <em>La Domination<\/em>, Paris, La D\u00e9couverte, 2014.<\/p>\n<p>&#8211; Weber (Max), <em>Le Savant et le politique<\/em>, Paris, Plon, 1959 [e.o. 1919].<\/p>\n<h3 style=\"text-align: center;\"><strong><u>CHAPITRE 3. Une organisation politique comp\u00e9titive\u00a0: champs &amp; march\u00e9s politiques<\/u><\/strong><\/h3>\n<p><strong>\u00a0<\/strong><strong>Section 1. La comp\u00e9tition d\u00e9mocratique<\/strong><\/p>\n<ul>\n<li><strong>1.<\/strong> Une comp\u00e9tition politique<\/li>\n<li><strong>2.<\/strong> Une comp\u00e9tition politique sp\u00e9cifique<\/li>\n<li><strong>3.<\/strong> Une comp\u00e9tition politique symbolique &amp; pacifique<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Section 2. Conqu\u00e9rir un march\u00e9 politique en proposant des biens politiques<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Section 3. Construction historique &amp; \u00e9volution des march\u00e9s politiques<\/strong><\/p>\n<ul>\n<li><strong>1.<\/strong> Les transactions en march\u00e9s restreints\u00a0: la monarchie parlementaire &amp; le suffrage censitaire (1815-1848)<\/li>\n<li><strong>2.<\/strong> Des march\u00e9s politiques censitaires aux march\u00e9s politiques de masse\u00a0: apprentissage du suffrage universel &amp; autonomisation du politique<\/li>\n<li><strong>3.<\/strong> L\u2019apparition d\u2019un nouveau type de personnel politique &amp; ses effets : l\u2019invention de l\u2019\u00e9lecteur (1800-1914) (Michel Offerl\u00e9, Alain Garrigou)<\/li>\n<\/ul>\n<p><span style=\"color: #339966;\"><strong>Ouverture : visionnage de la vid\u00e9o &#8220;Les Fran\u00e7ais et le vote de 1814 \u00e0 1870&#8221; (4&#8217;41), consultable ici : https:\/\/www.bing.com\/videos\/search?q=suffrage+censitaire&amp;&amp;view=detail&amp;mid=6A1777F35DE65EC7BA3F6A1777F35DE65EC7BA3F&amp;&amp;FORM=VRDGAR&amp;ru=%2Fvideos%2Fsearch%3Fq%3Dsuffrage%2Bcensitaire%26FORM%3DHDRSC3 et de la vid\u00e9o &#8220;Le droit de vote des femmes&#8221; (5&#8217;41), consultable ici : https:\/\/www.youtube.com\/watch?v=C3THYevbKNE<\/strong><\/span><\/p>\n<p><strong>Section 4. Le \u00ab\u00a0cens cach\u00e9\u00a0\u00bb (Daniel Gaxie)<\/strong><\/p>\n<ul>\n<li><strong>1.<\/strong> L\u2019illusion d\u00e9mocratique<\/li>\n<li><strong>2.<\/strong> Les in\u00e9galit\u00e9s de politisation<\/li>\n<\/ul>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Sch\u00e8mes de perception, d\u2019\u00e9valuation &amp; de classification des \u00e9v\u00e9nements &amp; des enjeux politiques<\/li>\n<li>La division sociale du travail<\/li>\n<li>Le concept de champ politique<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><strong>Section 5. Les \u00e9volutions r\u00e9centes : l\u2019unification des march\u00e9s politiques, l&#8217;augmentation de la non participation<\/strong><\/p>\n<ul>\n<li><strong>1.<\/strong> L\u2019intensification de la comp\u00e9tition<\/li>\n<li><strong>2.<\/strong> La rationalisation des pratiques politiques<\/li>\n<li><strong>3.<\/strong> La personnification de l\u2019univers politique<\/li>\n<li><strong>4.<\/strong> La collectivisation de l\u2019activit\u00e9 politique<\/li>\n<li><strong>5.<\/strong> Int\u00e9gration &amp; autonomisation des march\u00e9s politiques<\/li>\n<li><strong>6.<\/strong> Une non participation en hausse : non ou mal inscription, abstention intermittente ou syst\u00e9matique, votes blancs et nuls<\/li>\n<\/ul>\n<p><span style=\"color: #339966;\"><strong>Ouvertures et exercices : <\/strong><\/span><\/p>\n<ol>\n<li><span style=\"color: #339966;\"><strong>Visionnez cette interview de Daniel Gaxie, Professeur de Science politique \u00e0 l&#8217;Universit\u00e9 de Paris 1 &#8211; Panth\u00e9on-Sorbonne, sur les rapports ordinaires au politique<\/strong> (54&#8217;28) : https:\/\/www.politika.io\/fr\/entretien\/rapports-au-politique<\/span><\/li>\n<\/ol>\n<p><span style=\"color: #339966;\"><strong style=\"font-size: inherit;\">2. R<\/strong><strong style=\"font-size: inherit;\">\u00e9sumez et mettez en perspective, de mani\u00e8re argument\u00e9e, cette conf\u00e9rence de Patrick Lehingue, Professeur de Science politique \u00e0 l\u2019UPJV : \u00ab L\u2019\u00e9lection est-elle un rite d\u00e9mocratique d\u00e9pass\u00e9 ? \u00bb <\/strong><span style=\"font-size: inherit;\">(1h03) ; \u00e0 visionner ici :\u00a0<\/span><\/span><span style=\"color: #339966;\">https:\/\/webtv.u-picardie.fr\/watch_video.php?v=WX2O9RXO5BAY<\/span><\/p>\n<p><span style=\"color: #339966;\"><strong>3. Visionnage du film documentaire de septembre 2014 &#8220;J&#8217;ai pas vot\u00e9&#8221; (46&#8217;23)<\/strong>, consultable ici : https:\/\/www.bing.com\/videos\/search?q=sociologie+abstention+france&amp;ru=%2fvideos%2fsearch%3fq%3dsociologie%2babstention%2bfrance%26qs%3dn%26form%3dQBVR%26sp%3d-1%26pq%3dsociologie%2babstention%2bfrance%26sc%3d0-28%26sk%3d%26cvid%3dF9DA146102D342D383A24CEC942F3425&amp;view=detail&amp;mid=AA4DE48A1F4CAAD426FBAA4DE48A1F4CAAD426FB&amp;&amp;FORM=VDRVSR<\/span><\/p>\n<p><span style=\"color: #339966; font-size: inherit;\">4. <strong>Visionnez l&#8217;intervention de la politiste Aur\u00e9lia Troupel<\/strong>, Ma\u00eetresse de conf\u00e9rences en Science Politique \u00e0 l\u2019Universit\u00e9 de Montpellier, <strong>sur les votes blancs et nuls<\/strong> (dur\u00e9e : 3&#8217;23) + <strong>Lisez l&#8217;article de l&#8217;auteure<\/strong>, &#8220;Le vote blanc et nul, un porte-voix \u00e0 faible r\u00e9sonance&#8221;, <\/span><em style=\"color: #339966; font-size: inherit;\">The Conversation<\/em><span style=\"color: #339966; font-size: inherit;\">, 22 mai 2017, consultable ici : https:\/\/theconversation.com\/le-vote-blanc-et-nul-un-porte-voix-a-faible-resonance-77965<\/span><\/p>\n<p><strong><span style=\"color: #339966;\">Exercices propos\u00e9s sur le chapitre 3 :<\/span><\/strong><\/p>\n<ol>\n<li><span style=\"color: #339966;\"><strong>Vous \u00e9laborerez une fiche de lecture (pour les conseils m\u00e9thodologiques, vous vous reporterez \u00e0 la fiche technique du livret MTU) sur le texte suivant, gratuitement accessible en ligne sur le portail Persee :<\/strong><\/span><\/li>\n<\/ol>\n<p><span style=\"color: #339966;\">Alain Garrigou, \u00ab\u00a0Le secret de l\u2019isoloir\u00a0\u00bb, <em>Actes de la Recherche en Sciences Sociales<\/em>, n\u00b0 71-72, mars 1988, pp. 22-45. <\/span><\/p>\n<p><strong><span style=\"color: #339966;\">Vous montrerez en particulier comment les Fran\u00e7ais ont fait l\u2019apprentissage du vote et comment ils sont devenus \u00e9lecteurs.*<\/span><\/strong><\/p>\n<p><span style=\"color: #339966;\"><strong>2. Vous \u00e9laborerez une fiche de lecture sur le texte suivant, gratuitement accessible en ligne sur le portail Persee :<\/strong><\/span><\/p>\n<p><span style=\"color: #339966;\">Michel Offerl\u00e9, \u00ab\u00a0Le nombre de voix. Electeurs, partis et \u00e9lectorat socialistes \u00e0 la fin du XIX\u00e8me si\u00e8cle en France\u00a0\u00bb, <em>Actes de la Recherche en Sciences Sociales<\/em>, n\u00b0 71-72, 1988, pp. 5-21. <\/span><\/p>\n<p><strong><span style=\"color: #339966;\">Vous montrerez en particulier en quoi on peut dire que les \u00ab\u00a0donn\u00e9es \u00e9lectorales\u00a0\u00bb sont des construits sociaux.<\/span><\/strong><\/p>\n<p><span style=\"color: #339966;\"><strong>3. Vous \u00e9laborerez une fiche de lecture sur les textes suivants, gratuitement accessible en ligne sur le site OpenEdition :<\/strong><\/span><\/p>\n<p><span style=\"color: #339966;\">Olivier Ihl, \u00ab\u00a0<a style=\"color: #339966;\" href=\"http:\/\/www.scribd.com\/full\/16952108?access_key=key-19tbxjusvvslgd02umq1\">La civilit\u00e9 \u00e9lectorale\u00a0: vote et forclusion de la violence en France<\/a>\u00a0\u00bb, parties 1 &amp; 2, <em>Cultures et conflits<\/em>, n\u00b0 9-10, 1993, pp. 75-96.<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Attention, <u>une fiche de lecture n\u2019est pas un simple r\u00e9sum\u00e9 du texte<\/u>, mais suppose une mise en perspective critique (actualit\u00e9 des conclusions du texte, mise en perspective avec d\u2019autres textes ou travaux, \u00e9largissements possibles, critiques en cas de controverse scientifique, etc.). Veillez donc \u00e0 bien lire la fiche m\u00e9thodologique, et \u00e0 vous appuyer aussi sur le cours.<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #339966;\">4. Sur la base du cours et de vos lectures compl\u00e9mentaires, vous pourrez \u00e9laborer un plan d\u00e9taill\u00e9 de dissertation ou r\u00e9diger une dissertation compl\u00e8te (pour la m\u00e9thodologie, vous vous reporterez \u00e0 la fiche technique du livret MTU) sur l&#8217;un des sujets suivants :<\/span><\/strong><\/p>\n<ul>\n<li><strong><span style=\"color: #339966;\">Quelles ont \u00e9t\u00e9 les principales cons\u00e9quences politiques du passage du suffrage censitaire au suffrage universel en France en 1848 ?<\/span><\/strong><\/li>\n<li><strong><span style=\"color: #339966;\">En quoi peut-on dire que l\u2019\u00e9lecteur est une invention ?<\/span><\/strong><\/li>\n<li><strong style=\"font-size: inherit;\"><span style=\"color: #339966;\">La distribution sociale des comp\u00e9tences politiques<\/span><\/strong><\/li>\n<li><strong style=\"font-size: inherit;\"><span style=\"color: #339966;\">Les d\u00e9terminants sociaux des comportements \u00e9lectoraux<\/span><\/strong><\/li>\n<\/ul>\n<p><span style=\"color: #800080;\"><strong><u>Bibliographie pour le chapitre 3 (sont mis en gras les articles gratuitement accessibles en ligne, \u00e0 lire obligatoirement en compl\u00e9ment du cours)<\/u><\/strong><\/span><\/p>\n<p><strong>&#8211; <em>Actes de la Recherche en Sciences Sociales<\/em>, \u00ab\u00a0Votes\u00a0\u00bb, n\u00b0 140, 2001.<\/strong><\/p>\n<p>&#8211; Beaurepaire-Hernandez (Adeline), Guedj (J\u00e9r\u00e9my) [dir.], <em>L\u2019Entre-deux \u00e9lectoral. Une autre histoire de la repr\u00e9sentation politique en France (XIXe-XXe si\u00e8cles)<\/em>, Rennes, PUR, 2015.<\/p>\n<p><strong><u>&#8211; Bensoussan (David), \u00ab\u00a0Des notables bien vivants. La p\u00e9rennit\u00e9 de la notabilit\u00e9 traditionnelle en Bretagne dans l\u2019entre-deux-guerres\u00a0\u00bb, <em>Histoire@Politique. Politique, culture, soci\u00e9t\u00e9<\/em>, n\u00b0\u00a025, janvier-avril 2015 [en ligne].<\/u><\/strong><\/p>\n<p><strong><u>&#8211; Bourdieu (Pierre), \u00ab\u00a0 La repr\u00e9sentation politique. El\u00e9ments pour une th\u00e9orie du champ\u00a0\u00bb, <em>Actes de la recherche en sciences sociales<\/em>, n\u00b0 36\/37, f\u00e9vrier-mars 1981, pp. 3-24.<\/u><\/strong><\/p>\n<p>&#8211; Braconnier (C\u00e9line), Dormagen (Jean-Yves), <em>La D\u00e9mocratie de l\u2019abstention. Aux origines de la d\u00e9mobilisation \u00e9lectorale en milieu populaire<\/em>, Paris, Gallimard, coll. \u00ab Folio \u00bb, 2007.<\/p>\n<p><strong><u>&#8211; Chamouard (Aude), \u00ab\u00a0Existe-t-il des notables socialistes sous la Troisi\u00e8me R\u00e9publique\u00a0?\u00a0\u00bb, <em>Histoire@Politique. Politique, culture, soci\u00e9t\u00e9<\/em>, n\u00b0 25, janvier-avril 2015 [en ligne].<\/u><\/strong><\/p>\n<p>&#8211; Christin (Olivier), Vox Populi<em>. Une histoire du vote avant le suffrage universel<\/em>, Paris, Seuil, 2014.<\/p>\n<p>&#8211; Cohen (Antonin), Lacroix (Bernard), Riutort (Philippe) [dir.], <em>Les Formes de l\u2019activit\u00e9 politique. El\u00e9ments d\u2019analyse sociologique XVIIIe-XXe si\u00e8cle<\/em>, Paris, PUF, 2006.<\/p>\n<p>&#8211; D\u00e9loye (Yves), Ihl (Olivier), <em>L\u2019Acte de vote, <\/em>Paris, Presses de Sciences Po, 2008.<\/p>\n<p>&#8211; D\u00e9loye (Yves), <em>Les Voix de Dieu. Pour une autre histoire du suffrage \u00e9lectoral\u00a0: le clerg\u00e9 catholique fran\u00e7ais et le vote, XIXe<\/em><em>&#8211;<\/em><em>XXe si\u00e8cles, <\/em>Paris, Fayard, 2006.<\/p>\n<p>&#8211; D\u00e9loye (Yves), D\u00e9z\u00e9 (Alexandre), Maurer (Sophie) [dir.],<em> Institutions, \u00e9lections, opinion. M\u00e9langes en l\u2019honneur de Jean-Luc Parodi,<\/em> Paris, Presses de Sciences Po, coll. \u00ab\u00a0Acad\u00e9mique\u00a0\u00bb, 2014.<\/p>\n<p>&#8211; Demazi\u00e8re (Didier), Le Lidec (Patrick) [dir.], <em>Les Mondes du travail politique. Les \u00e9lus et leurs entourages<\/em>, Rennes, PUR, 2014.<\/p>\n<p>&#8211; Dulong (Delphine), <em>La Construction du champ politique<\/em>, Paris, PUR, 2010.<\/p>\n<p><strong><u>&#8211; Faucher (Florence), Hay (Colin), \u00ab\u00a0Les rituels de vote en France et au Royaume-Uni\u00a0\u00bb, <em>RFSP<\/em>, vol. 65, n\u00b0 2, 2015.<\/u><\/strong><\/p>\n<p>&#8211; Garrigou (Alain), \u00ab\u00a0Client\u00e9lisme et vote sous la IIIe R\u00e9publique\u00a0\u00bb, in Briquet (Jean-Louis), Sawicki (Fr\u00e9d\u00e9ric) [dir.], <em>Le Client\u00e9lisme dans les soci\u00e9t\u00e9s contemporaines<\/em>, Paris, PUF, 1998.<\/p>\n<p><strong><u>&#8211; Garrigou (Alain), \u00ab\u00a0La construction sociale du vote. F\u00e9tichisme et raison instrumentale\u00a0\u00bb, <em>Politix<\/em>, n\u00b0 22, 1993, pp. 5-42.<\/u><\/strong><\/p>\n<p>&#8211; Garrigou (Alain), <em>Histoire sociale du suffrage universel en France, <\/em>Paris, Seuil, 2002.<\/p>\n<p>&#8211; Garrigou (Alain), <em>Le Vote et la vertu. Comment les Fran\u00e7ais sont devenus \u00e9lecteurs<\/em>, Paris, Presses de la FNSP, 1992.<\/p>\n<p>&#8211; Gaxie (Daniel), <em>La D\u00e9mocratie repr\u00e9sentative<\/em>, Paris, Montchrestien, coll. \u00ab\u00a0Clefs Politique\u00a0\u00bb, 3<sup>e<\/sup> \u00e9d. 2000.<\/p>\n<p>&#8211; Gaxie (Daniel), <em>Le Cens cach\u00e9<\/em>. <em>In\u00e9galit\u00e9s culturelles et s\u00e9gr\u00e9gation politique<\/em>, Paris, Seuil, 1978, dern. \u00e9d. 2000.<\/p>\n<p>&#8211; <em>Histoire@Politique<\/em>, n\u00b0 25, janvier-avril 2015\u00a0: \u00ab\u00a0Notables et R\u00e9publique en France de 1870 \u00e0 nos jours\u00a0\u00bb.<\/p>\n<p>&#8211; Huard (Raymond), <em>Le Suffrage universel et la d\u00e9mocratie 1846-1946<\/em>, Paris, Aubier, 1991.<\/p>\n<p><strong><u>&#8211; Ihl (Olivier), \u00ab\u00a0L\u2019urne \u00e9lectorale. Formes et usages d\u2019une technique de vote\u00a0\u00bb, <em>Revue Fran\u00e7aise de Science Politique<\/em>, vol. 43, n\u00b0 1, 1993, pp. 30-60.<\/u><\/strong><\/p>\n<p>&#8211; Ihl (Olivier), <em>Le Vote<\/em>, Paris, Montchrestien, coll. \u00ab\u00a0Clefs Politique\u00a0\u00bb, 2<sup>e<\/sup> \u00e9d, 2000.<\/p>\n<p>&#8211; Jardin (Andr\u00e9), Tudesq (Andr\u00e9 Jean), <em>La France des notables, 1815-1848,<\/em> Paris, Seuil, 1973.<\/p>\n<p>&#8211; Lehingue (Patrick), <em>Le Vote. Approches sociologiques de l\u2019institution et des comportements \u00e9lectoraux<\/em>, Paris, La D\u00e9couverte, coll. \u00ab\u00a0Grands Rep\u00e8res Manuels\u00a0\u00bb, 2011.<\/p>\n<p>&#8211; Mazeaud (Alice) [dir.], <em>Pratiques de la repr\u00e9sentation politique<\/em>, Rennes, PUR, 2014.<\/p>\n<p>&#8211; Neveu (Erik), <em>Sociologie politique des probl\u00e8mes publics<\/em>, Paris, Armand Colin, 2015.<\/p>\n<p>&#8211; Offerl\u00e9 (Michel) [dir.], <em>La Profession politique XIXe-XXe si\u00e8cles<\/em>, Paris, Belin, 1999.<\/p>\n<p><strong><u>&#8211; Offerl\u00e9 (Michel), \u00ab\u00a0L\u2019\u00e9lecteur et ses papiers. Enqu\u00eate sur les cartes et les listes \u00e9lectorales (1849-1939)\u00a0\u00bb, <em>Gen\u00e8ses<\/em>, n\u00b0 13, 1993, pp. 29-53.<\/u><\/strong><\/p>\n<p>&#8211; Offerl\u00e9 (Michel), \u00ab\u00a0Mobilisation \u00e9lectorale et invention du citoyen. L\u2019exemple du milieu urbain \u00e0 la fin du XIX\u00e8me si\u00e8cle\u00a0\u00bb, in Gaxie (Daniel) [dir.], <em>Explication du vote<\/em>, Paris, Presses de Science Po, 1985, pp. 149-174.<\/p>\n<p>&#8211; Offerl\u00e9 (Michel), <em>Les Partis politiques<\/em>, Paris, PUF, coll. \u00ab\u00a0Que sais-je\u00a0\u00bb, 1987.<\/p>\n<p>&#8211; Offerl\u00e9 (Michel), <em>Un Homme, une voix\u00a0? Histoire du suffrage universel<\/em>, Paris, Gallimard, coll. \u00ab\u00a0D\u00e9couvertes\u00a0\u00bb, 1995.<\/p>\n<p>&#8211; Poirmeur (Yves), <em>Les Partis politiques. Du XIX<sup>e<\/sup> au XXI<sup>e<\/sup> si\u00e8cle en France<\/em>, Paris, LGDJ\/Lextenso Editions, coll. \u00ab\u00a0Syst\u00e8mes Perspectives\u00a0\u00bb, 2014.<\/p>\n<p>&#8211; <em>R\u00e9seaux<\/em>, 2014, vol. 5, n\u00b0 187\u00a0: \u00ab\u00a0Le travail politique par et pour les m\u00e9dias\u00a0\u00bb.<\/p>\n<p>&#8211; Rosanvallon (Pierre), <em>Le Sacre du citoyen. Histoire du suffrage universel<\/em>, Paris, Gallimard, 1992.<\/p>\n<p>&#8211; <em>Savoir\/agir<\/em>, n\u00b0 31, mars 2015\u00a0: \u00ab\u00a0La d\u00e9mocratie\u00a0\u00bb (articles de Nathalie Ethuin, R\u00e9mi Lefebvre, Alexandre D\u00e9z\u00e9, Pierre Mongaux, Julien Fretel, H\u00e9lo\u00efse Nez, Lamprini Rori\u2026)<\/p>\n<p>&#8211; <em>Savoir\/agir<\/em>, n\u00b0 32, juin 2015\u00a0: \u00ab\u00a0R\u00e9inventer les partis politiques\u00a0\u00bb (articles de Michel Offerl\u00e9, Daniel Gaxie, Patrick Lehingue. Jos\u00e9-Luis Moreno Pestanas, Patrick Champagne\u2026)<\/p>\n<p>&#8211; Sauv\u00eatre (Pierre), <em>Quand les socialistes inventaient l\u2019avenir (1825-1860)<\/em>, Paris, La D\u00e9couverte, 2015.<\/p>\n<p>&#8211; Tudesq (Andr\u00e9-Jean), \u00ab\u00a0Les comportements \u00e9lectoraux sous le r\u00e9gime censitaire\u00a0\u00bb, in Gaxie (Daniel), [dir.], <em>Explication du vote<\/em>, Paris, Presses de Science Po, 1985, pp. 106-125.<\/p>\n<p><strong><u>&#8211; Voillot (Christophe), Qu\u00e9ro (Laurent), \u00ab\u00a0Du suffrage censitaire au suffrage universel\u00a0: \u00e9volution ou r\u00e9volution des pratiques \u00e9lectorales\u00a0?\u00a0\u00bb, <em>Actes de la Recherche en Sciences Sociales<\/em>, n\u00b0 140, 2001, pp. 34-40.<\/u><\/strong><\/p>\n<p>&#8211; Weber (Max), <em>Economie et soci\u00e9t\u00e9<\/em>, Paris, Plon, coll. \u00ab\u00a0Agora\u00a0\u00bb, 1995 [e.o. 1921].<\/p>\n<p>&#8211; Weber (Max), <em>Le Savant et le politique<\/em>, Paris, Plon, 1959 [e.o. 1919].<\/p>\n<p>&#8211; Weber (Max), <em>Le M\u00e9tier et la vocation d&#8217;homme politique<\/em>, Paris, Plon, coll. \u00ab\u00a0Biblioth\u00e8ques 10\/18\u00a0\u00bb, 2001.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cours d\u2019Isabelle CHARPENTIER icharpentier@yahoo.fr ou isabelle.charpentier@u-picardie.fr L2S3 \u2013 UE Disciplinaire Compl\u00e9mentaire Sociologie ; CM optionnel de 24 h \u2013 3 ects SOCIOLOGIE POLITIQUE R\u00e9sum\u00e9 L\u2019organisation politique des soci\u00e9t\u00e9s contemporaines pr\u00e9sente trois caract\u00e9ristiques principales : elle repose sur une diff\u00e9renciation du politique des autres activit\u00e9s sociales, elle est de type \u00e9tatique et elle est comp\u00e9titive. Cette &#8230; <a title=\"Sociologie politique (CM L2S3)\" class=\"read-more\" href=\"http:\/\/amiens-sociologie.fr\/index.php\/sociologie-politique-cm-et-td-l2s3-et-l3s5\/\">Read more<span class=\"screen-reader-text\">Sociologie politique (CM L2S3)<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/pages\/276"}],"collection":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":9,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/pages\/276\/revisions"}],"predecessor-version":[{"id":3035,"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/pages\/276\/revisions\/3035"}],"wp:attachment":[{"href":"http:\/\/amiens-sociologie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}